{"id":108035,"date":"2021-11-15T08:00:00","date_gmt":"2021-11-15T07:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=108035"},"modified":"2021-11-18T10:46:17","modified_gmt":"2021-11-18T09:46:17","slug":"xrechnung-nicht-in-der-praxis-angekommen","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/xrechnung-nicht-in-der-praxis-angekommen\/","title":{"rendered":"XRechnung nicht in der Praxis angekommen"},"content":{"rendered":"\n<p>Seit Ende 2020 nimmt der Bund gem\u00e4\u00df einer EU-Richtlinie nur noch Rechnungen in elektronischer Form entgegen. Nach und nach folgen jetzt die einzelnen Bundesl\u00e4nder mit der Pflicht der Rechnungsstellung im Format XRechnung. <\/p>\n\n\n\n<p>Zum Stand der technischen Umsetzung der elektronischen Rechnung hat die Deutschsprachige SAP-Anwendergruppe e. V. (DSAG) eine Mitgliederumfrage durchgef\u00fchrt. Dabei kam heraus: Zwei Drittel der befragten Unternehmen haben bereits eine L\u00f6sung zur Erstellung von XRechnungen im Einsatz, intensiv genutzt wird diese bislang aber von der Mehrheit noch nicht.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-908151068\"><div id=\"great-3820595488\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Vielf\u00e4ltigkeit verlangsamt Digitalisierung<\/h3>\n\n\n\n<p>Die technischen und rechtlichen Rahmenbedingungen f\u00fcr die XRechnung stehen, gleichwohl sind die Ergebnisse der DSAG-Umfrage durchwachsen: Von insgesamt 145 befragten Unternehmen hatten zwar 66 Prozent bereits eine L\u00f6sung zur Erstellung des neuen Rechnungsformates im Einsatz. Eingef\u00fchrt wurde diese jeweils h\u00e4lftig durch die eigene IT-Abteilung beziehungsweise gemeinsam mit Beratungsunternehmen. Knapp 20 Prozent befinden sich derzeit noch im Planungsstadium. Zur selben Zeit aber hatten rund 52 Prozent bislang \u00fcberhaupt erst zwischen null und 100 Rechnungen als XRechnung verschickt.<\/p>\n\n\n\n<p>\u201e<em>Die verschiedenen XRechnung-L\u00f6sungen im Bund und den Bundesl\u00e4ndern schaffen eine Vielf\u00e4ltigkeit, die in der EU einzigartig ist. Gleichzeitig hemmt genau dies den entscheidenden Schritt hin zur Digitalisierung<\/em>\u201c, erkl\u00e4rt Colin Bl\u00f6cher, Sprecher der Arbeitsgruppe Electronic Invoicing und Real-time Reporting bei der DSAG. \u201e<em>Selbst gro\u00dfe Konzerne und untergeordnete Landesbeh\u00f6rden verlangen unterschiedliche Versandwege wie Peppol, E-Mail, manuelle Eingabe, FTP oder De-Mail. Andere EU-L\u00e4nder haben dies wesentlich effizienter und damit kostensparender f\u00fcr Unternehmen gel\u00f6st<\/em>.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">H\u00e4ufigster Transportweg: E-Mail<\/h3>\n\n\n\n<p>18 Prozent der Befragten haben die SAP-eigene L\u00f6sung SAP Document Compliance im Einsatz. Mit ihr lassen sich XRechnungen in SAP ERP und S\/4 Hana erstellen und \u00fcber Peppol, E-Mail oder ZUGFeRD versenden. Rund 55 Prozent verwenden hierf\u00fcr Partnerl\u00f6sungen innerhalb oder au\u00dferhalb von SAP. F\u00fcr den Versand nutzt mit 52 Prozent immer noch eine Mehrheit den E-Mail-Verkehr. Es folgen (mit 25 Prozent) der Upload \u00fcber \u00f6ffentliche Portale (ZRE des Bundes, OZG-RE der Bundesdruckerei), Peppol (22 Prozent), ZUGFeRD (20 Prozent) und Portale von Drittanbietern (12 Prozent).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/10\/202110_dsag.jpg\"><img decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/10\/202110_dsag.jpg\" alt=\"\" class=\"wp-image-108022\"\/><\/a><figcaption><em>Versandkan\u00e4le von Rechnungen. \u00dcber welche Kan\u00e4le versenden Sie die Rechnungen in Ihrem Umfeld? (Mehrfachantworten m\u00f6glich) n=95 \u00a9 DSAG Juli 2021<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Peppol agiert technisch wie ein Einschreiben mit R\u00fcckschein, was zurzeit alle anderen Versandarten nur bedingt oder gar nicht leisten. \u201e<em>Dem Versandweg Peppol geh\u00f6rt die Zukunft, da Unternehmen und Beh\u00f6rden auf diese Weise schlanke Prozesse realisieren und wirklich Kosten einsparen k\u00f6nnen<\/em>\u201c, prognostiziert Bernd Nowack, stellvertretender Sprecher der Arbeitsgruppe Rechnungswesen bei der DSAG. \u201e<em>Die anderen Transportarten in Kombination mit entsprechenden Formaten treiben IT- und Prozesskosten eher in die H\u00f6he, denn sie erfordern wegen des unsichereren Transports strengere Kontrolle und gegebenenfalls Nacharbeiten<\/em>.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Kein Potenzial f\u00fcr B2B<\/h3>\n\n\n\n<p>Lieferanten, die auf die elektronische Rechnung im Format XRechnung umsteigen, sparen Papier- und Portokosten und profitieren von schnellerem elektronischen Versand von Peppol und damit potenziell schnellerer Bezahlung. Deshalb sollte zu erwarten sein, dass sich nach dem Rechnungsverkehr mit \u00f6ffentlichen Einrichtungen die XRechnung auch im B2B-Gesch\u00e4ft durchsetzen wird. Genau dies aber steht laut DSAG-Umfrage noch nicht an: Bislang sehen lediglich 13 Prozent der befragten Unternehmen hier weiteres Potenzial f\u00fcr die XRechnung. F\u00fcr die DSAG-Sprecher sind die Ergebnisse der Mitgliederumfrage daher nicht \u00fcberraschend.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die technischen und rechtlichen Rahmenbedingungen f\u00fcr die XRechnung stehen, gleichwohl sind die Ergebnisse einer DSAG-Umfrage zum Thema durchwachsen.<\/p>\n","protected":false},"author":2155,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[4,39822],"tags":[350,601,273,143,38298],"coauthors":[38132],"class_list":["post-108035","post","type-post","status-publish","format-standard","hentry","category-management","category-mag-21-10","tag-b2b","tag-digitalisierung","tag-dsag","tag-management","tag-xrechnung","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","image-100":"","image-480":"","image-640":"","image-720":"","image-960":"","image-1168":"","image-1440":"","image-1920":"","1536x1536":"","2048x2048":"","trp-custom-language-flag":"","bricks_large_16x9":"","bricks_large":"","bricks_large_square":"","bricks_medium":"","bricks_medium_square":"","profile_24":"","profile_48":"","profile_96":"","profile_150":"","profile_300":""},"post_excerpt_stackable_v2":"<p>Die technischen und rechtlichen Rahmenbedingungen f\u00fcr die XRechnung stehen, gleichwohl sind die Ergebnisse einer DSAG-Umfrage zum Thema durchwachsen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/management\/\" rel=\"category tag\">Business-Management<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-21-10\/\" rel=\"category tag\">MAG 21-10<\/a>","author_info_v2":{"name":"DSAG e.V.","url":"https:\/\/e3mag.com\/de\/author\/dsag-e-v\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/108035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2155"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=108035"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/108035\/revisions"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=108035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=108035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=108035"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=108035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}