{"id":10084,"date":"2017-03-01T00:20:21","date_gmt":"2017-02-28T23:20:21","guid":{"rendered":"http:\/\/e3mag.com\/?p=10084"},"modified":"2019-03-11T14:48:38","modified_gmt":"2019-03-11T13:48:38","slug":"es-muss-nicht-immer-ariba-sein","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/es-muss-nicht-immer-ariba-sein\/","title":{"rendered":"Es muss nicht immer Ariba sein"},"content":{"rendered":"<p>Die Anwender von SAP Supplier Relationship Management (SRM) und Supplier Lifecycle Management (SLC) stehen unter Zugzwang. Das f\u00fcr 2025 angek\u00fcndigte Wartungsende f\u00fcr die Business Suite 7 macht ein Nachdenken \u00fcber neue Optionen f\u00fcr den SAP-basierten Einkauf erforderlich.<\/p>\n<p>SAP selbst fokussiert das Ariba-Netzwerk und die Echtzeit-ERP-Suite S\/4 Hana. Als Public-Cloud-L\u00f6sung kommt Ariba jedoch nicht f\u00fcr jede Einkaufsorganisation infrage. Ein Grund daf\u00fcr sind Datenschutzbedenken, ein anderer, dass sich nur standardisierte Einkaufsprozesse mit sehr geringen Anpassungsbedarfen abbilden lassen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-892490086\"><div id=\"great-1765259291\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n<p>Branchentypische und regionale Besonderheiten, wie der GAEB-Standard f\u00fcr Baudienstleistungen, bleiben in \u00f6ffentlichen Cloud-L\u00f6sungen wie Ariba meist auf der Strecke.<\/p>\n<h3>Dann also S\/4 Hana?<\/h3>\n<p>Vieles spricht daf\u00fcr. So enth\u00e4lt die neue Business Suite die gleichen Procurement-Funktionen, die bisher als SAP Materials Management (SAP MM) verf\u00fcgbar sind. Da S\/4 auf der In-memory-Plattform Hana basiert, profitieren die Nutzer von deutlichen Performance-Steigerungen sowie besseren M\u00f6glichkeiten f\u00fcr Ad-hoc-Reporting, Analysen und Simulationen.<\/p>\n<p>Durch die intuitive Oberfl\u00e4chentechnologie SAP Fiori greifen sie unkomplizierter und schneller auf alle ben\u00f6tigten Einkaufsfunktionen zu. Und das von jedem beliebigen Endger\u00e4t aus, \u00fcberall und jederzeit.<\/p>\n<p>F\u00fcr die Anwender der klassischen SAP-Einkaufsl\u00f6sungen hat die S\/4-Hana-Strategie unterschiedliche Folgen: W\u00e4hrend SAP SLC direkt in S\/4 Hana aufgeht und jedem Kunden standardm\u00e4\u00dfig zur Verf\u00fcgung steht, kommt f\u00fcr das weitverbreitete, bew\u00e4hrte SAP SRM sp\u00e4testens ab 2025 das Aus.<\/p>\n<p>W\u00e4hrend die Zeit l\u00e4uft, stehen SRM-Nutzer aktuell vor der Frage, ob sie weiterhin in ihr Einkaufssystem investieren sollen, um erforderliche Innovationen umzusetzen.<\/p>\n<p>Neben angestrebten Effizienzgewinnen sind es vor allem gesetzliche Vorgaben, die die digitale Transformation im Einkauf derzeit vorantreiben. Ein Beispiel ist die neuen EU-Vergaberichtlinien f\u00fcr \u00f6ffentliche Ausschreibungen.<\/p>\n<h3>Ausrichtung an Roadmap<\/h3>\n<p>Prinzipiell empfiehlt es sich, eine Investitionsentscheidung im SAP-basierten Einkauf an der allgemeinen S\/4-Hana-Roadmap eines Unternehmens auszurichten. Ist in den kommenden drei Jahren kein Umstieg auf S\/4 Hana vorgesehen? Dann lohnen sich Investitionen in die vorhandenen SRM- und SLC-L\u00f6sungen.<\/p>\n<p>Da diese Einkaufsl\u00f6sungen mindestens noch bis Ende 2025 in der Wartung sind, werden die Kunden mit regelm\u00e4\u00dfigen Enhancement-Packages und Sicherheits-Updates versorgt.<\/p>\n<p>Soll der S\/4-Umstieg allerdings innerhalb der n\u00e4chsten drei Jahre erfolgen, ist es ratsam, mit gr\u00f6\u00dferen Systemanpassungen bis zu diesem Zeitpunkt zu warten. Aktuelle Anforderungen k\u00f6nnen die Einkaufsorganisationen mit speziellen Cloud-L\u00f6sungen abdecken.<\/p>\n<p>Eine weitere Alternative bieten integrierte \u00dcbergangsl\u00f6sungen, bei denen zahlreiche n\u00fctzliche Procurement-Funktionen direkt in die vorhandene SAP-Infrastruktur eingebunden werden.<\/p>\n<p>Dies hat f\u00fcr die Anwender zahlreiche Vorteile, vor allem kaufm\u00e4nnischer Natur. Da das SAP SRM vollst\u00e4ndig verzichtbar wird, kann es sich um ein kostenneutrales Projekt handeln.<\/p>\n<p>Durch Einsparungen bei der entfallenden Hardware werden Investitionen in die neue L\u00f6sung kompensiert. Zudem sinken die Gesamtbetriebskosten (TCO), da die zuvor komplexe Systemumgebung aus ERP, SRM, Katalog und Contentmanagement auf ein einziges System reduziert wird.<\/p>\n<p>Die direkte Integration in die ERP-Landschaft steigert die Datensicherheit. Au\u00dferdem sorgt sie f\u00fcr eine konsistente Datenbasis und erleichtert die sp\u00e4tere Migration auf S\/4 Hana.<\/p>\n<p>Mit einer integrierten \u00dcbergangsl\u00f6sung k\u00f6nnen Unternehmen ihren Einkauf fit f\u00fcr das digitale Zeitalter machen, ohne in die Ariba-Cloud oder kurzfristig auf S\/4 wechseln zu m\u00fcssen.<\/p>\n<p>Nur ein kleinerer Teil plant, laut einer aktuellen DSAG-Investitionsumfrage, einen S\/4-Umstieg in den n\u00e4chsten drei Jahren. Zwei Drittel der befragten Unternehmen gaben an, in diesem Zeitraum am herk\u00f6mmlichen ERP festhalten zu wollen oder noch unentschlossen zu sein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An Ariba oder S\/4 Hana scheint im SAP-basierten Einkauf kein Weg mehr vorbei\u00adzuf\u00fchren. Jedoch gibt es attraktive Alternativen, um auf die Anforderungen der Digitalisierung kurzfristig zu reagieren.  <\/p>\n","protected":false},"author":154,"featured_media":2445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[19,7,6386],"tags":[162,6711,39,73,982,5010,5176,6713,6708,6710,6714],"coauthors":[23048],"class_list":["post-10084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-b2b2c-kolumne","category-meinung","category-mag-1703","tag-ariba","tag-business-suite-7","tag-cloud","tag-erp","tag-hana-s4","tag-public-cloud","tag-sap-fiori","tag-sap-mm","tag-sap-srm","tag-slc","tag-tco","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",400,173,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-768x332.jpg",768,332,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-100x43.jpg",100,43,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-480x207.jpg",480,207,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-640x276.jpg",640,276,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-720x311.jpg",720,311,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-960x415.jpg",960,415,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",600,259,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",600,259,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/B2B2C-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>An Ariba oder S\/4 Hana scheint im SAP-basierten Einkauf kein Weg mehr vorbei\u00adzuf\u00fchren. Jedoch gibt es attraktive Alternativen, um auf die Anforderungen der Digitalisierung kurzfristig zu reagieren.  <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/b2b2c-kolumne\/\" rel=\"category tag\">B2B2C-Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-1703\/\" rel=\"category tag\">MAG 17-03<\/a>","author_info_v2":{"name":"Mike R\u00fcbsamen, 2Bits","url":"https:\/\/e3mag.com\/de\/author\/mike-ruebsamen\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/10084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/154"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=10084"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/10084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/2445"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=10084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=10084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=10084"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=10084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}